{"id":103187,"date":"2025-02-15T17:47:16","date_gmt":"2025-02-15T17:47:16","guid":{"rendered":"https:\/\/tvbrazilusa.com\/2025\/02\/15\/carros-eletricos-byd-adquire-direitos-de-exploracao-de-litio-no-brasil\/"},"modified":"2025-02-15T17:47:18","modified_gmt":"2025-02-15T17:47:18","slug":"carros-eletricos-byd-adquire-direitos-de-exploracao-de-litio-no-brasil","status":"publish","type":"post","link":"https:\/\/tvbrazilusa.com\/pt\/2025\/02\/15\/carros-eletricos-byd-adquire-direitos-de-exploracao-de-litio-no-brasil\/","title":{"rendered":"CARROS EL\u00c9TRICOS: BYD adquire direitos de explora\u00e7\u00e3o de l\u00edtio no Brasil"},"content":{"rendered":"<p> <script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8864793242727901\"\r\n     crossorigin=\"anonymous\"><\/script><br \/>\n<\/p>\n<div id=\"taboola-read-more\" style=\"display:block; width:100%\">\n<p>A chinesa BYD adquiriu direitos de minera\u00e7\u00e3o em uma \u00e1rea rica em l\u00edtio pr\u00f3ximo \u00e0 cidade de Coronel Murta, no Vale do Jequitinhonha, em Minas Gerais. O local fica a cerca de 12h da f\u00e1brica da montadora em Cama\u00e7ari, na Bahia, e \u00e9 conhecido como \u201cVale do L\u00edtio\u201d, por conta da ampla disponibilidade do mineral no solo.\n<\/p>\n<p>Segundo documentos obtidos pela ag\u00eancia de not\u00edcias Reuters, a aquisi\u00e7\u00e3o dos direitos de explora\u00e7\u00e3o do local, feita em 2023 por meio de uma subsidi\u00e1ria da empresa, chamada \u201cExplora\u00e7\u00e3o Mineral do Brasil\u201d e criada em maio daquele ano, estabelece a entrada da BYD no mercado de minerais no Ocidente. O Brasil \u00e9 o maior consumidor da montadora fora da China.<\/p>\n<p>Os documentos aos quais a Reuters teve acesso mostram que a empresa foi criada com um investimento inicial de R$ 4 milh\u00f5es e teve lucro de R$ 230 mil j\u00e1 no 1\u00ba ano. Relat\u00f3rio de outubro de 2024 mostra que a empresa \u201cest\u00e1 na fase de pesquisa, sem nenhuma movimenta\u00e7\u00e3o financeira ou receita operacional\u201d.\n<\/p>\n<p>A Reuters apontou o crescente interesse da BYD sobre o mercado sul-americano de minerais. A ag\u00eancia relatou que a montadora foi uma das 6 empresas liberadas para fazer ofertas para um projeto de explora\u00e7\u00e3o de l\u00edtio no Chile, em 2024.\n<\/p>\n<p><strong>AM\u00c9RICA DO SUL \u00c9 RICA EM L\u00cdTIO<\/strong>\n<\/p>\n<p>Relat\u00f3rio do US Geological Survey de 2023 mostrou que Argentina, Bol\u00edvia e Chile agregam 60% das reservas conhecidas de l\u00edtio do planeta. O min\u00e9rio \u00e9 usado na fabrica\u00e7\u00e3o de baterias de alto desempenho usadas em carros el\u00e9tricos e aparelhos eletr\u00f4nicos como notebooks e smartphones e est\u00e1 no centro do debate sobre o desenvolvimento tecnol\u00f3gico no mundo.\n<\/p>\n<p>Os 3 pa\u00edses est\u00e3o em est\u00e1gios diferentes na explora\u00e7\u00e3o do min\u00e9rio. O Chile \u00e9 o \u00fanico que avan\u00e7ou para a extra\u00e7\u00e3o nacional do recurso. O presidente chileno, Gabriel Boric, anunciou em abril um projeto para criar uma empresa estatal para controlar a explora\u00e7\u00e3o do min\u00e9rio.\n<\/p>\n<p>O governo ser\u00e1 o acionista majorit\u00e1rio da empresa, mas a produ\u00e7\u00e3o ser\u00e1 feita em parceria com empresas privadas estrangeiras. O Chile \u00e9 o 2\u00ba maior produtor de l\u00edtio hoje \u2013respons\u00e1vel por cerca de 30% da oferta mundial\u2013 s\u00f3 atr\u00e1s da Austr\u00e1lia.\n<\/p>\n<p>O presidente da Bol\u00edvia, Luis Arce, assinou contrato com o cons\u00f3rcio chin\u00eas CBC \u2013composto pelas Contemporary Amperex Technology, Brunp e China Molybdenum Company\u2013 para a extra\u00e7\u00e3o de l\u00edtio em Coipasa e Uyuni.\n<\/p>\n<p>O investimento de cerca de US$ 1 bilh\u00e3o ser\u00e1 destinado \u00e0 instala\u00e7\u00e3o de duas plantas industriais para a explora\u00e7\u00e3o do min\u00e9rio. Cada uma ser\u00e1 capaz de produzir cerca de 25.000 toneladas de carbonato de l\u00edtio por ano.\n<\/p>\n<p>A Bol\u00edvia tem a maior reserva de l\u00edtio do mundo com 21 milh\u00f5es de toneladas, mas n\u00e3o tem recursos e ferramentas para explorar o min\u00e9rio e ainda n\u00e3o determinou se isso ser\u00e1 feito por empresas estrangeiras.\n<\/p>\n<p><strong>VALE DO L\u00cdTIO BRASILEIRO<\/strong>\n<\/p>\n<p>O Brasil lan\u00e7ou em maio de 2023 a campanha Vale do L\u00edtio. O objetivo \u00e9 transformar as cidades do nordeste e norte de Minas Gerais em um centro de produ\u00e7\u00e3o do min\u00e9rio. O governo do Estado afirma que existem 45 jazidas de l\u00edtio no nordeste do Estado, o que pode aumentar em mais de 20 vezes a produ\u00e7\u00e3o brasileira.\n<\/p>\n<p>A Reuters aponta que visitas recentes de representantes dos Estados Unidos, Ar\u00e1bia Saudita e China demonstram o interesse global no Brasil como um mercado para a corrida do acesso a minerais estrat\u00e9gicos. A ag\u00eancia ressalta tamb\u00e9m que o posicionamento geol\u00f3gico das reservas de l\u00edtio no Brasil permite uma extra\u00e7\u00e3o facilitada, ao contr\u00e1rio dos outros pa\u00edses sul-americanos que t\u00eam grandes reservas.\n<\/p>\n<p><strong>RESGATE DE TRABALHADORES<\/strong>\n<\/p>\n<p>Em dezembro de 2023, uma for\u00e7a-tarefa do Minist\u00e9rio P\u00fablico do Trabalho, da Pol\u00edcia Federal e de outras organiza\u00e7\u00f5es resgatou 163 trabalhadores chineses em \u201ccondi\u00e7\u00f5es an\u00e1logas \u00e0 de escravos\u201d e interditou parcialmente as obras para constru\u00e7\u00e3o de uma f\u00e1brica da montadora BYD em Cama\u00e7ari, na Bahia.\n<\/p>\n<p>Eles teriam assinado contratos com cl\u00e1usulas abusivas, segundo reportagem da Folha de S.Paulo. Contratado pelo empreiteiro Jinjiang, o grupo teria sido obrigado a entregar ao contratante o passaporte, pagar US$ 900 (que s\u00f3 seriam devolvidos ap\u00f3s 6 meses de trabalho) e ter a maior parte do seu sal\u00e1rio retido para envio \u00e0 China.\n<\/p>\n<p>Fonte: Poder360              <\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/diariodobrasilnoticias.com.br\/noticia\/carros-eletricos-byd-adquire-direitos-de-exploracao-de-litio-no-brasil-67b0b055f3d87\">Source link <\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>A chinesa BYD adquiriu direitos de minera\u00e7\u00e3o em uma \u00e1rea rica em l\u00edtio pr\u00f3ximo \u00e0 cidade de Coronel Murta, no Vale do Jequitinhonha, em Minas Gerais. O local fica a&hellip;<\/p>","protected":false},"author":1,"featured_media":103188,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[16],"tags":[123,2448,5313,1267],"class_list":["post-103187","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-brasil","tag-diario","tag-noticia","tag-noticias"],"_links":{"self":[{"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/posts\/103187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/comments?post=103187"}],"version-history":[{"count":1,"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/posts\/103187\/revisions"}],"predecessor-version":[{"id":103189,"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/posts\/103187\/revisions\/103189"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/media\/103188"}],"wp:attachment":[{"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/media?parent=103187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/categories?post=103187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/tags?post=103187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}