{"id":105321,"date":"2025-02-22T00:24:07","date_gmt":"2025-02-22T00:24:07","guid":{"rendered":"https:\/\/tvbrazilusa.com\/2025\/02\/22\/agora-bolsonaro-diz-ter-se-equivocado-ao-falar-que-caga-para-prisao\/"},"modified":"2025-02-22T00:24:08","modified_gmt":"2025-02-22T00:24:08","slug":"agora-bolsonaro-diz-ter-se-equivocado-ao-falar-que-caga-para-prisao","status":"publish","type":"post","link":"https:\/\/tvbrazilusa.com\/pt\/2025\/02\/22\/agora-bolsonaro-diz-ter-se-equivocado-ao-falar-que-caga-para-prisao\/","title":{"rendered":"AGORA: Bolsonaro diz ter se equivocado ao falar que &#8216;caga&#8217; para pris\u00e3o"},"content":{"rendered":"<p> <script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8864793242727901\"\r\n     crossorigin=\"anonymous\"><\/script><br \/>\n<\/p>\n<div id=\"taboola-read-more\" style=\"display:block; width:100%\">\n<p>O ex-presidente Jair Bolsonaro (PL) disse nesta 6\u00aa feira (21.fev.2025) ter se equivocado ao falar que \u201ccaga\u201d para eventual pris\u00e3o. A declara\u00e7\u00e3o foi r\u00e1pida e se deu em um evento do PL (Partido Liberal), em Bras\u00edlia.\n<\/p>\n<p>Na 5\u00aa feira (20.fev), ele afirmou que \u201ccaga\u201d para a pris\u00e3o, demonstrando n\u00e3o estar pressionado por eventual pris\u00e3o pela acusa\u00e7\u00e3o. A fala se deu durante o seu 1\u00ba discurso depois da den\u00fancia.<\/p>\n<p>Bolsonaro foi denunciado pela PGR (Procuradoria-Geral da Rep\u00fablica) na 3\u00aa feira (18.fev) por suposta tentativa de golpe de Estado. O STF (Supremo Tribunal Federal) julgar\u00e1 o caso.\n<\/p>\n<p>Especialistas consultados pelo Poder360 estimam que Bolsonaro pode receber uma pena de pris\u00e3o 12 a 43 anos.\n<\/p>\n<p>Segundo a den\u00fancia, a organiza\u00e7\u00e3o da qual o ex-presidente fazia parte tinha como objetivo impedir a posse de Lula. O texto atribui a Bolsonaro 5 crimes:\n<\/p>\n<p>aboli\u00e7\u00e3o violenta do Estado democr\u00e1tico de Direito;<br \/>golpe de Estado; integrar organiza\u00e7\u00e3o criminosa armada; <br \/>dano qualificado contra o patrim\u00f4nio da Uni\u00e3o; e <br \/>deteriora\u00e7\u00e3o de patrim\u00f4nio tombado.<br \/>Al\u00e9m de comentar brevemente sobre a eventual pris\u00e3o, o ex-presidente falou sobre os protestos marcados para 16 de mar\u00e7o. Reiterou que a prioridade \u00e9 pautar o PL da anistia.\n<\/p>\n<p>PL E BIG TECHS <br \/>O PL realizou nesta semana o \u201c1\u00ba Semin\u00e1rio Nacional de Comunica\u00e7\u00e3o do Partido Liberal\u201d. O objetivo do evento foi discutir estrat\u00e9gias da sigla nas redes sociais. Estiveram presentes pessoas ligadas ao X (ex-Twitter), Google e Kwai. O foco foram as elei\u00e7\u00f5es de 2026.\n<\/p>\n<p>No local do congresso, havia banners com frases mostrando a uni\u00e3o entre as big techs e o PL. \u201cO Partido Liberal e as big techs unidos pela liberdade de express\u00e3o\u201d, dizia um dos banners. \u201cAs maiores big techs do mundo com o maior partido do Brasil\u201d, afirmava outro.\n<\/p>\n<p>Al\u00e9m do ex-presidente, o evento contou com discursos do presidente da legenda, Valdemar Costa Neto, do senador Rog\u00e9rio Marinho (RN) e do l\u00edder da bancada na C\u00e2mara, S\u00f3stenes Cavalcante (RJ). Valdemar e Bolsonaro n\u00e3o se cruzaram, j\u00e1 que est\u00e3o impedidos de manter contato por ordem judicial.\n<\/p>\n<p>Fonte: Poder 360              <\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/diariodobrasilnoticias.com.br\/noticia\/agora-bolsonaro-diz-ter-se-equivocado-ao-falar-que-caga-para-prisao-67b8f5dfc44b4\">Source link <\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>O ex-presidente Jair Bolsonaro (PL) disse nesta 6\u00aa feira (21.fev.2025) ter se equivocado ao falar que \u201ccaga\u201d para eventual pris\u00e3o. A declara\u00e7\u00e3o foi r\u00e1pida e se deu em um evento&hellip;<\/p>","protected":false},"author":1,"featured_media":105322,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[16],"tags":[123,2448,5313,1267],"class_list":["post-105321","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-brasil","tag-diario","tag-noticia","tag-noticias"],"_links":{"self":[{"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/posts\/105321","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/comments?post=105321"}],"version-history":[{"count":1,"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/posts\/105321\/revisions"}],"predecessor-version":[{"id":105323,"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/posts\/105321\/revisions\/105323"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/media\/105322"}],"wp:attachment":[{"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/media?parent=105321"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/categories?post=105321"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/tags?post=105321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}