{"id":112442,"date":"2025-03-20T01:38:04","date_gmt":"2025-03-20T01:38:04","guid":{"rendered":"https:\/\/tvbrazilusa.com\/2025\/03\/20\/boston-dynamics-revela-avancos-impressionantes-na-mobilidade-do-robo-humanoide-atlas-veja-video\/"},"modified":"2025-03-20T01:38:06","modified_gmt":"2025-03-20T01:38:06","slug":"boston-dynamics-revela-avancos-impressionantes-na-mobilidade-do-robo-humanoide-atlas-veja-video","status":"publish","type":"post","link":"https:\/\/tvbrazilusa.com\/pt\/2025\/03\/20\/boston-dynamics-revela-avancos-impressionantes-na-mobilidade-do-robo-humanoide-atlas-veja-video\/","title":{"rendered":"Boston Dynamics revela avan\u00e7os impressionantes na mobilidade do rob\u00f4 humanoide Atlas; VEJA V\u00cdDEO"},"content":{"rendered":"<p> <script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8864793242727901\"\r\n     crossorigin=\"anonymous\"><\/script><br \/>\n<\/p>\n<div>\n<figure class=\"post-image\">\n<\/figure>\n<p>            <span style=\"font-size: 12px\">Reprodu\u00e7\u00e3o<\/span><\/p>\n<p>            <!-- end metas --><br \/>\n            <!-- ADS --><\/p>\n<div id=\"taboola-read-more\" style=\"display:block; width:100%\">\n<p>A Boston Dynamics, renomada empresa de rob\u00f3tica, recentemente apresentou avan\u00e7os impressionantes na capacidade de movimenta\u00e7\u00e3o do seu rob\u00f4 humanoide Atlas. Conhecido por sua agilidade e versatilidade, o Atlas tem evolu\u00eddo constantemente, e as \u00faltimas atualiza\u00e7\u00f5es destacam um marco significativo em sua autonomia e precis\u00e3o de movimentos.\n<\/p>\n<p>De acordo com a empresa, o rob\u00f4 agora \u00e9 capaz de realizar tarefas complexas de forma totalmente aut\u00f4noma, como manipular objetos em ambientes din\u00e2micos e se adaptar a mudan\u00e7as em tempo real. Um exemplo recente mostrou o Atlas movendo capas de motor entre cont\u00eaineres e um carrinho de sequenciamento, utilizando aprendizado de m\u00e1quina para detectar e se orientar no ambiente sem depender de comandos pr\u00e9-programados ou teleoperados. Essa capacidade reflete anos de pesquisa para integrar for\u00e7a, percep\u00e7\u00e3o e mobilidade em um \u00fanico sistema.<\/p>\n<p>Al\u00e9m disso, a Boston Dynamics demonstrou o uso de pol\u00edticas de aprendizado por refor\u00e7o, desenvolvidas em parceria com o Instituto RAI, permitindo que o Atlas replique movimentos humanos capturados por trajes especiais. Isso abre portas para aplica\u00e7\u00f5es que v\u00e3o desde tarefas industriais mon\u00f3tonas at\u00e9 cen\u00e1rios mais complexos, como resgates ou opera\u00e7\u00f5es em ambientes desafiadores.<br \/>Com um design el\u00e9trico que supera as limita\u00e7\u00f5es de vers\u00f5es hidr\u00e1ulicas anteriores, o Atlas est\u00e1 sendo projetado para ir al\u00e9m das capacidades humanas, oferecendo uma amplitude de movimento excepcional. Esses avan\u00e7os refor\u00e7am o compromisso da empresa em criar rob\u00f4s que n\u00e3o apenas imitem, mas tamb\u00e9m ampliem as possibilidades do trabalho humano, apontando para um futuro onde a rob\u00f3tica pode transformar ind\u00fastrias e a sociedade como um todo.\n<\/p>\n<p><strong>ASSISTA:<\/strong>\n<\/p>\n<p>Fonte: @diretodaamerica \/ X              <\/p>\n<\/div>\n<p>                        <!-- Scripts para conteudo --><\/p>\n<p>            <!-- .\/Scripts para conteudo --><br \/>\n            <!-- .\/Mat\u00e9ria --><\/p>\n<div class=\"row mt-3\">\n<div class=\"col-sm-6\">\n                <!-- Whatsapp channel 3--><br \/>\n                <a href=\"https:\/\/chat.whatsapp.com\/B8Qy6Erx4kb6yTzj3kaDco\" target=\"_blank\"><br \/>\n                  <img decoding=\"async\" src=\"https:\/\/diariodobrasilnoticias.com.br\/assets-site\/images\/bot_whatsapp.png\"\/><\/a>\n              <\/div>\n<div class=\"col-sm-6\">\n                <a href=\"https:\/\/t.me\/+_4gTmi5LKo03OTM5\" target=\"_blank\"><br \/>\n                  <img decoding=\"async\" src=\"https:\/\/diariodobrasilnoticias.com.br\/assets-site\/images\/bot_telegram.png\"\/><\/a>\n              <\/div>\n<\/p><\/div>\n<p>            <!-- end post-navigation --><\/p>\n<p>              <!-- end row --><\/p>\n<p>              <!-- end col-12-->\n                      <\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/diariodobrasilnoticias.com.br\/noticia\/boston-dynamics-revela-avancos-impressionantes-na-mobilidade-do-robo-humanoide-atlas-veja-video-67db43cda91de\">Source link <\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Reprodu\u00e7\u00e3o A Boston Dynamics, renomada empresa de rob\u00f3tica, recentemente apresentou avan\u00e7os impressionantes na capacidade de movimenta\u00e7\u00e3o do seu rob\u00f4 humanoide Atlas. Conhecido por sua agilidade e versatilidade, o Atlas tem&hellip;<\/p>","protected":false},"author":1,"featured_media":112443,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[16],"tags":[123,2448,5313,1267],"class_list":["post-112442","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-brasil","tag-diario","tag-noticia","tag-noticias"],"_links":{"self":[{"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/posts\/112442","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/comments?post=112442"}],"version-history":[{"count":1,"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/posts\/112442\/revisions"}],"predecessor-version":[{"id":112444,"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/posts\/112442\/revisions\/112444"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/media\/112443"}],"wp:attachment":[{"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/media?parent=112442"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/categories?post=112442"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/tags?post=112442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}