{"id":133548,"date":"2026-05-13T16:20:00","date_gmt":"2026-05-13T16:20:00","guid":{"rendered":"https:\/\/tvbrazilusa.com\/2026\/05\/13\/benedito-goncalves-tem-parecer-favoravel-para-assumir-corregedoria-do-cnj\/"},"modified":"2026-05-13T16:21:01","modified_gmt":"2026-05-13T16:21:01","slug":"benedito-goncalves-tem-parecer-favoravel-para-assumir-corregedoria-do-cnj","status":"publish","type":"post","link":"https:\/\/tvbrazilusa.com\/pt\/2026\/05\/13\/benedito-goncalves-tem-parecer-favoravel-para-assumir-corregedoria-do-cnj\/","title":{"rendered":"Benedito Gon\u00e7alves tem parecer favor\u00e1vel para assumir corregedoria do CNJ"},"content":{"rendered":"<p> <script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8864793242727901\"\r\n     crossorigin=\"anonymous\"><\/script><br \/>\n<\/p>\n<div id=\"cd-article-content\">\n<p>O senador <strong><a href=\"https:\/\/claudiodantas.com.br\/cid\/\" data-type=\"post\" data-id=\"77466\">Cid Gomes (PSB-CE)<\/a><\/strong> apresentou nesta manh\u00e3 (13) parecer favor\u00e1vel \u00e0 indica\u00e7\u00e3o de <strong><a href=\"https:\/\/claudiodantas.com.br\/tag\/benedito-goncalves\/\" data-type=\"post_tag\" data-id=\"12930\">Benedito Gon\u00e7alves<\/a><\/strong>, do Superior Tribunal de Justi\u00e7a (STJ), ao cargo de <strong><a href=\"https:\/\/www.cnj.jus.br\/corregedoriacnj\/\" target=\"_blank\" rel=\"noopener\">corregedor Nacional de Justi\u00e7a<\/a><\/strong>. A leitura do parecer foi feita na Comiss\u00e3o de Constitui\u00e7\u00e3o e Justi\u00e7a (CCJ) do Senado.<\/p>\n<p><a href=\"https:\/\/whatsapp.com\/channel\/0029VaTFkH2HVvTbkE883x1x\" target=\"_blank\" class=\"whatsapp-channel-message\" rel=\"noopener\">\u2705 Siga o canal do Claudio Dantas no WhatsApp<\/a><\/p>\n<p>A sabatina de Gon\u00e7alves est\u00e1 marcada para a pr\u00f3xima quarta (20). A indica\u00e7\u00e3o partiu do presidente do STJ, Herman Benjamin, ap\u00f3s elei\u00e7\u00e3o interna em 14 de abril. <\/p>\n<p>Caso seja aprovado pelo Senado e nomeado pelo presidente da Rep\u00fablica, Gon\u00e7alves assume o mandato no CNJ no bi\u00eanio 2026\/2028.<\/p>\n<p>O Conselho Nacional de Justi\u00e7a (CNJ) \u00e9 formado por 15 integrantes com mandato de dois anos. Um deles, indicado pelo STJ, acumula obrigatoriamente a fun\u00e7\u00e3o de corregedor Nacional de Justi\u00e7a.<\/p>\n<p>A corregedoria \u00e9 respons\u00e1vel por receber reclama\u00e7\u00f5es contra magistrados, abrir sindic\u00e2ncias e fiscalizar a atua\u00e7\u00e3o disciplinar do Judici\u00e1rio em todo o pa\u00eds. A nomea\u00e7\u00e3o depende de aprova\u00e7\u00e3o por maioria absoluta do Senado e posterior ato do Executivo.<\/p>\n<p>Ao apresentar o relat\u00f3rio, Cid Gomes destacou a trajet\u00f3ria do indicado e defendeu sua aptid\u00e3o para o cargo: \u201cPara mim \u00e9 uma honra especial fazer a relatoria desta indica\u00e7\u00e3o para a corregedoria do nosso Conselho Nacional de Justi\u00e7a (CNJ), espa\u00e7o e tarefa na qual n\u00e3o tenho d\u00favida ele se haver\u00e1 com grande responsabilidade, com grande efici\u00eancia, enobrecendo e zelando pelo conceito da Justi\u00e7a no nosso pa\u00eds\u201d<\/p>\n<p>Benedito Gon\u00e7alves ficou conhecido ap\u00f3s epis\u00f3dio em que recebeu \u201ctapinhas\u201d no rosto de Lula durante a posse de Moraes como presidente do TSE em 2022. O petista foi quem o indicou ao cargo no STJ em 2008.<\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><\/figure>\n<\/div>\n<\/div>\n<p><script type=\"bc5a3312e3ce06923a151623-text\/javascript\">!function(f,b,e,v,n,t,s){if(f.fbq)return;n=f.fbq=function(){n.callMethod?n.callMethod.apply(n,arguments):n.queue.push(arguments)};if(!f._fbq)f._fbq=n;n.push=n;n.loaded=!0;n.version='2.0';n.queue=[];t=b.createElement(e);t.async=!0;t.src=v;s=b.getElementsByTagName(e)[0];s.parentNode.insertBefore(t,s)}(window,document,'script','https:\/\/connect.facebook.net\/en_US\/fbevents.js');fbq('init','1423865622537930');fbq('track','PageView');<\/script><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/claudiodantas.com.br\/benedito-goncalves-favoravel-corregedor-cnj\/\">Source link <\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>O senador Cid Gomes (PSB-CE) apresentou nesta manh\u00e3 (13) parecer favor\u00e1vel \u00e0 indica\u00e7\u00e3o de Benedito Gon\u00e7alves, do Superior Tribunal de Justi\u00e7a (STJ), ao cargo de corregedor Nacional de Justi\u00e7a. A&hellip;<\/p>","protected":false},"author":1,"featured_media":133549,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[16],"tags":[],"class_list":["post-133548","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/posts\/133548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/comments?post=133548"}],"version-history":[{"count":1,"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/posts\/133548\/revisions"}],"predecessor-version":[{"id":133550,"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/posts\/133548\/revisions\/133550"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/media\/133549"}],"wp:attachment":[{"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/media?parent=133548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/categories?post=133548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/tags?post=133548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}