{"id":136394,"date":"2026-07-14T17:34:32","date_gmt":"2026-07-14T17:34:32","guid":{"rendered":"https:\/\/tvbrazilusa.com\/2026\/07\/14\/o-tiro-saiu-pela-culatra-moraes-mirou-flavio-e-criou-uma-crise-no-stf\/"},"modified":"2026-07-14T17:34:32","modified_gmt":"2026-07-14T17:34:32","slug":"o-tiro-saiu-pela-culatra-moraes-mirou-flavio-e-criou-uma-crise-no-stf","status":"publish","type":"post","link":"https:\/\/tvbrazilusa.com\/pt\/2026\/07\/14\/o-tiro-saiu-pela-culatra-moraes-mirou-flavio-e-criou-uma-crise-no-stf\/","title":{"rendered":"O TIRO SAIU PELA CULATRA \u2014 Moraes mirou Fl\u00e1vio e criou uma crise no STF"},"content":{"rendered":"<p><iframe  width=\"580\" height=\"385\" src=\"https:\/\/www.youtube.com\/embed\/75xDpbW8OFQ?modestbranding=1\" frameborder=\"0\" allowfullscreen><\/iframe><br \/>\n<br \/>#tvflorida #tvfloridausa #cortestvfloridausa<br \/>\nSe ainda n\u00e3o for inscrito, inscreva-se em nosso clube de membros, clicando abaixo:<\/p>\n<p>Parceria com a Auriverde Brasil<br \/>\n@auriverdebrasil<br \/>\nLike, Inscreva-se e Torne-se um Membro do Canal da @auriverdebrasil<\/p>\n<p>Seja nosso patrono, atrav\u00e9s do link:<\/p>\n<p>Para conferir todos os v\u00eddeos e not\u00edcias, acesse nosso website e clique no link do menu &#8220;Ao vivo&#8221; ou baixe nosso app e clique no link &#8220;TV&#8221; para assistir a TV online.<\/p>\n<p>Assista nossa programa\u00e7\u00e3o 24 horas por dia:<\/p>\n<p>Deixamos aqui algumas op\u00e7\u00f5es para ajudar a manter nossos projetos online:<\/p>\n<p>Por PIX atrav\u00e9s do E-mail: info@tvfloridausa.com<br \/>\nSe ainda n\u00e3o for inscrito, inscreva-se em nosso canal de cortes e confiram nosso conte\u00fado por l\u00e1. <\/p>\n<p>Ou ainda sendo nosso patrono, atrav\u00e9s do link:<\/p>\n<p>Baixe aqui nosso aplicativo totalmente gr\u00e1tis!<\/p>\n<p>Android e IOS<\/p>\n<p>Agora temos um canal exclusivo da TV Brazil USA na plataforma:<\/p>\n<p>Inscrevam-se para nao perder nada. 24 horas ao vivo!<br \/>\n#paulofigueiredo #tudoconsta #eduardobolsonaro #jairbolsonaro #direita #conservadorismo<br \/>\n<br \/><a href=\"https:\/\/www.youtube.com\/watch?v=75xDpbW8OFQ\">source<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>#tvflorida #tvfloridausa #cortestvfloridausa Se ainda n\u00e3o for inscrito, inscreva-se em nosso clube de membros, clicando abaixo: Parceria com a Auriverde Brasil @auriverdebrasil Like, Inscreva-se e Torne-se um Membro do Canal&hellip;<\/p>","protected":false},"author":1,"featured_media":136395,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[17],"tags":[36147,733,31294,70,36146,425,160,32750,871,29530,753],"class_list":["post-136394","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-programas","tag-criou","tag-crise","tag-culatra","tag-flavio","tag-mirou","tag-moraes","tag-pela","tag-saiu","tag-stf","tag-tiro","tag-uma"],"_links":{"self":[{"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/posts\/136394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/comments?post=136394"}],"version-history":[{"count":0,"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/posts\/136394\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/media\/136395"}],"wp:attachment":[{"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/media?parent=136394"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/categories?post=136394"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvbrazilusa.com\/pt\/wp-json\/wp\/v2\/tags?post=136394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}